{"id":5282,"date":"2019-11-14T14:28:49","date_gmt":"2019-11-14T13:28:49","guid":{"rendered":"http:\/\/www.balidetox.com\/en\/?page_id=5282"},"modified":"2019-12-25T18:43:28","modified_gmt":"2019-12-25T17:43:28","slug":"gallery","status":"publish","type":"page","link":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][page_submenu alignment=&#8221;center&#8221; sticky=&#8221;true&#8221; bg_color=&#8221;#02662a&#8221; link_color=&#8221;#ffffff&#8221;][page_link title=&#8221;Bali SPA Massage:&#8221; id=&#8221;1544045605174-0-5&#8243; tab_id=&#8221;1544045605177-8&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/&#8221;][\/page_link][page_link link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#onama&#8221; title=&#8221;About&#8221; id=&#8221;1544036939-1-36&#8243; tab_id=&#8221;1544036970599-6&#8243;] [\/page_link][page_link title=&#8221;Massages&#8221; id=&#8221;1569338287716-0-3&#8243; tab_id=&#8221;1569338287724-8&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#massages&#8221;][\/page_link][page_link link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery&#8221; title=&#8221;Gallery&#8221; id=&#8221;1544036939-2-51&#8243; tab_id=&#8221;1544036970774-10&#8243;] [\/page_link][page_link title=&#8221;Pricelist&#8221; id=&#8221;1544045406085-0-9&#8243; tab_id=&#8221;1544045406088-9&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#cenovnik&#8221;][\/page_link][page_link title=&#8221;Gift voucher&#8221; id=&#8221;1544037025590-0-4&#8243; tab_id=&#8221;1544037025596-2&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#poklon&#8221;][\/page_link][page_link title=&#8221;Location&#8221; id=&#8221;1544037093885-0-1&#8243; tab_id=&#8221;1544037093889-5&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#lokacija&#8221;][\/page_link][page_link title=&#8221;Contact&#8221; id=&#8221;1544037125429-0-9&#8243; tab_id=&#8221;1544037125432-6&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#kontakt&#8221;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; id=&#8221;galerija&#8221; row_name=&#8221;Galerija&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;5647,5653,5648,5650,5649,5651,5652,5655,5656,5657,5293,5658&#8243; layout=&#8221;fullwidth&#8221; masonry_style=&#8221;true&#8221; bypass_image_cropping=&#8221;true&#8221; item_spacing=&#8221;default&#8221; gallery_style=&#8221;3&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;600&#215;400&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;]<div class=\"sharing-default-minimal\"><div class=\"nectar-social default\" data-position=\"left\" data-color-override=\"override\"><div class=\"nectar-social-inner\"><a class='facebook-share nectar-sharing' href='#' title='Share this'>  <i class='fa fa-facebook'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='twitter-share nectar-sharing' href='#' title='Share this'> <i class='fa icon-salient-x-twitter'><\/i> <span class='social-text'>Share<\/span> <\/a><a class='linkedin-share nectar-sharing' href='#' title='Share this'> <i class='fa fa-linkedin'><\/i> <span class='social-text'>Share<\/span> <\/a><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][page_submenu alignment=&#8221;center&#8221; sticky=&#8221;true&#8221; bg_color=&#8221;#02662a&#8221; link_color=&#8221;#ffffff&#8221;][page_link title=&#8221;Bali SPA Massage:&#8221; id=&#8221;1544045605174-0-5&#8243; tab_id=&#8221;1544045605177-8&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/&#8221;][\/page_link][page_link link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#onama&#8221; title=&#8221;About&#8221; id=&#8221;1544036939-1-36&#8243; tab_id=&#8221;1544036970599-6&#8243;] [\/page_link][page_link title=&#8221;Massages&#8221; id=&#8221;1569338287716-0-3&#8243; tab_id=&#8221;1569338287724-8&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#massages&#8221;][\/page_link][page_link link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery&#8221; title=&#8221;Gallery&#8221; id=&#8221;1544036939-2-51&#8243; tab_id=&#8221;1544036970774-10&#8243;] [\/page_link][page_link title=&#8221;Pricelist&#8221; id=&#8221;1544045406085-0-9&#8243; tab_id=&#8221;1544045406088-9&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#cenovnik&#8221;][\/page_link][page_link title=&#8221;Gift voucher&#8221; id=&#8221;1544037025590-0-4&#8243; tab_id=&#8221;1544037025596-2&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#poklon&#8221;][\/page_link][page_link title=&#8221;Location&#8221; id=&#8221;1544037093885-0-1&#8243; tab_id=&#8221;1544037093889-5&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#lokacija&#8221;][\/page_link][page_link title=&#8221;Contact&#8221; id=&#8221;1544037125429-0-9&#8243; tab_id=&#8221;1544037125432-6&#8243; link_url=&#8221;https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#kontakt&#8221;][\/page_link][\/page_submenu][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; equal_height=&#8221;yes&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; id=&#8221;galerija&#8221; row_name=&#8221;Galerija&#8221; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_row_inner column_margin=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;left-right&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;5647,5653,5648,5650,5649,5651,5652,5655,5656,5657,5293,5658&#8243; layout=&#8221;fullwidth&#8221; masonry_style=&#8221;true&#8221; bypass_image_cropping=&#8221;true&#8221; item_spacing=&#8221;default&#8221; gallery_style=&#8221;3&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;600&#215;400&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;40&#8243; overlay_strength=&#8221;0.3&#8243; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column centered_text=&#8221;true&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_link_target=&#8221;_self&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; bg_image_animation=&#8221;none&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":5658,"parent":3581,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5282","page","type-page","status-publish","has-post-thumbnail"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bali Detox Centre Belgrade\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Gallery - Bali DETOX &amp; SPA Massage\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/\" \/>\n\t\t<meta property=\"fb:app_id\" content=\"303499063009567\" \/>\n\t\t<meta property=\"fb:admins\" content=\"100000365536208\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-11-14T13:28:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-12-25T17:43:28+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/balidetox.bg\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@balispamassage\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Gallery - Bali DETOX &amp; SPA Massage\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.balidetox.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/#listItem\",\"name\":\"Bali SPA Massage Center\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/#listItem\",\"position\":2,\"name\":\"Bali SPA Massage Center\",\"item\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#listItem\",\"name\":\"Gallery\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#listItem\",\"position\":3,\"name\":\"Gallery\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/#listItem\",\"name\":\"Bali SPA Massage Center\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/#organization\",\"name\":\"Bali Detox Centar\",\"description\":\"Proffesional massage, detoxification and body relax\",\"url\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/balidetoxcentar\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC9WtmRg-V1uVEZrdHeMtSgg\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#webpage\",\"url\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/\",\"name\":\"Gallery - Bali DETOX & SPA Massage\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/12\\\/massage-in-belgrade.jpg\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#mainImage\",\"width\":800,\"height\":533,\"caption\":\"Massage Belgrade\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/bali-spa-massage-center\\\/gallery\\\/#mainImage\"},\"datePublished\":\"2019-11-14T14:28:49+01:00\",\"dateModified\":\"2019-12-25T18:43:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/\",\"name\":\"Bali Detox Centre Belgrade\",\"description\":\"Proffesional massage, detoxification and body relax\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.balidetox.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Gallery - Bali DETOX & SPA Massage","description":"","canonical_url":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.balidetox.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#listItem","name":"Bali SPA Massage Center"}},{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#listItem","position":2,"name":"Bali SPA Massage Center","item":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#listItem","name":"Gallery"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#listItem","position":3,"name":"Gallery","previousItem":{"@type":"ListItem","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/#listItem","name":"Bali SPA Massage Center"}}]},{"@type":"Organization","@id":"https:\/\/www.balidetox.com\/en\/#organization","name":"Bali Detox Centar","description":"Proffesional massage, detoxification and body relax","url":"https:\/\/www.balidetox.com\/en\/","sameAs":["https:\/\/www.instagram.com\/balidetoxcentar\/","https:\/\/www.youtube.com\/channel\/UC9WtmRg-V1uVEZrdHeMtSgg"]},{"@type":"WebPage","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#webpage","url":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/","name":"Gallery - Bali DETOX & SPA Massage","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.balidetox.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg","@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#mainImage","width":800,"height":533,"caption":"Massage Belgrade"},"primaryImageOfPage":{"@id":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/#mainImage"},"datePublished":"2019-11-14T14:28:49+01:00","dateModified":"2019-12-25T18:43:28+01:00"},{"@type":"WebSite","@id":"https:\/\/www.balidetox.com\/en\/#website","url":"https:\/\/www.balidetox.com\/en\/","name":"Bali Detox Centre Belgrade","description":"Proffesional massage, detoxification and body relax","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.balidetox.com\/en\/#organization"}}]},"og:locale":"en_GB","og:site_name":"Bali Detox Centre Belgrade","og:type":"article","og:title":"Gallery - Bali DETOX &amp; SPA Massage","og:url":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/","fb:app_id":"303499063009567","fb:admins":"100000365536208","og:image":"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg","og:image:secure_url":"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg","og:image:width":800,"og:image:height":533,"article:published_time":"2019-11-14T13:28:49+00:00","article:modified_time":"2019-12-25T17:43:28+00:00","article:publisher":"https:\/\/www.facebook.com\/balidetox.bg","twitter:card":"summary_large_image","twitter:site":"@balispamassage","twitter:title":"Gallery - Bali DETOX &amp; SPA Massage","twitter:image":"https:\/\/www.balidetox.com\/en\/wp-content\/uploads\/sites\/2\/2019\/12\/massage-in-belgrade.jpg"},"aioseo_meta_data":{"post_id":"5282","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-22 09:41:54","updated":"2025-06-05 13:17:52","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.balidetox.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/\" title=\"Bali SPA Massage Center\">Bali SPA Massage Center<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGallery\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.balidetox.com\/en"},{"label":"Bali SPA Massage Center","link":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/"},{"label":"Gallery","link":"https:\/\/www.balidetox.com\/en\/bali-spa-massage-center\/gallery\/"}],"_links":{"self":[{"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/pages\/5282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/comments?post=5282"}],"version-history":[{"count":0,"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/pages\/5282\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/pages\/3581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/media\/5658"}],"wp:attachment":[{"href":"https:\/\/www.balidetox.com\/en\/wp-json\/wp\/v2\/media?parent=5282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}